{"id":5148,"date":"2024-06-12T13:42:23","date_gmt":"2024-06-12T11:42:23","guid":{"rendered":"https:\/\/www.fairtrade.es\/?p=5148&#038;preview=true&#038;preview_id=5148"},"modified":"2024-06-12T13:43:09","modified_gmt":"2024-06-12T11:43:09","slug":"el-trabajo-infantil-se-puede-abordar-paso-a-paso-y-programa-a-programa","status":"publish","type":"post","link":"https:\/\/www.fairtrade.es\/pt\/comercio-justo-exploracao-infantil-2\/","title":{"rendered":"O trabalho infantil pode ser abordado passo a passo e programa por programa."},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-5150\" src=\"https:\/\/www.fairtrade.es\/wp-content\/uploads\/2024\/06\/Bananas-Dominican-Republic-Las-Mercedes-2020-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.fairtrade.es\/wp-content\/uploads\/2024\/06\/Bananas-Dominican-Republic-Las-Mercedes-2020-300x200.jpg 300w, https:\/\/www.fairtrade.es\/wp-content\/uploads\/2024\/06\/Bananas-Dominican-Republic-Las-Mercedes-2020-1024x683.jpg 1024w, https:\/\/www.fairtrade.es\/wp-content\/uploads\/2024\/06\/Bananas-Dominican-Republic-Las-Mercedes-2020-768x512.jpg 768w, https:\/\/www.fairtrade.es\/wp-content\/uploads\/2024\/06\/Bananas-Dominican-Republic-Las-Mercedes-2020-1536x1024.jpg 1536w, https:\/\/www.fairtrade.es\/wp-content\/uploads\/2024\/06\/Bananas-Dominican-Republic-Las-Mercedes-2020-2048x1366.jpg 2048w, https:\/\/www.fairtrade.es\/wp-content\/uploads\/2024\/06\/Bananas-Dominican-Republic-Las-Mercedes-2020-18x12.jpg 18w, https:\/\/www.fairtrade.es\/wp-content\/uploads\/2024\/06\/Bananas-Dominican-Republic-Las-Mercedes-2020-scaled.jpg 2560w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Alrededor de 1,5 millones de ni\u00f1os trabajan en las plantaciones de cacao en Costa de Marfil y Ghana, donde se producen dos tercios del cacao del mundo, seg\u00fan un estudio de NORC de la Universidad de Chicago.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Fairtrade entiende que <\/span><b>la pobreza es una de las causas fundamentales del trabajo infantil,<\/b><span style=\"font-weight: 400;\"> y aunque no podemos resolver este problema end\u00e9mico, estamos tomando medidas para marcar la diferencia, incluido el apoyo a iniciativas que refuerzan los derechos de los ni\u00f1os y ponen fin a pr\u00e1cticas nocivas, como nuestro <\/span><b>Programa de Prevenci\u00f3n y Remediaci\u00f3n del Trabajo Infantil y el Trabajo Forzoso.\u00a0\u00a0<\/b><\/p>\n<p><b>Cuatro organizaciones de peque\u00f1os productores ya se est\u00e1n beneficiando<\/b><\/p>\n<p><span style=\"font-weight: 400;\">El programa, puesto en marcha en 2023, est\u00e1 empezando a tomar forma. Este verano, cuatro organizaciones de peque\u00f1os productores - CANN Cooperative, DAVO Cooperative, SOCAMEA Cooperative en Costa de Marfil, y\u00a0 ABOCFA Cooperative en Ghana - recibir\u00e1n m\u00e1s de 80.000 euros de financiaci\u00f3n que les permitir\u00e1n comenzar a implementar proyectos en sus comunidades locales. Se trata de <\/span><b>las primeras organizaciones de peque\u00f1os productores cuyas propuestas ser\u00e1n financiadas.\u00a0\u00a0<\/b><\/p>\n<p><span style=\"font-weight: 400;\">La Cooperativa CANN y la Cooperativa DAVO se centrar\u00e1n en la remodelaci\u00f3n de las escuelas, en particular utilizar\u00e1n los fondos para construir nuevas aulas para los ni\u00f1os locales. La Cooperativa DAVO agregar\u00e1 ba\u00f1os, paneles solares y un pozo que abastecer\u00e1 a la escuela con agua potable.\u00a0\u00a0\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La Cooperativa SOCAMEA proporcionar\u00e1 a los ni\u00f1os de sus comunidades locales bicicletas para ayudarles a asistir a la escuela. En algunos casos, los ni\u00f1os viven lejos y, por lo tanto, sin un transporte adecuado, asistir a la escuela suele ser imposible. Comprar\u00e1n 120 bicicletas y cascos y construir\u00e1n un garaje para bicicletas.\u00a0\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Y en Ghana, la Cooperativa ABOCFA renovar\u00e1 y ampliar\u00e1 la actual escuela primaria. Utilizar\u00e1n los fondos para ayudar a los ni\u00f1os con discapacidades f\u00edsicas proporcion\u00e1ndoles materiales educativos y ayud\u00e1ndoles a acceder a la atenci\u00f3n m\u00e9dica. Adem\u00e1s, tambi\u00e9n trabajar\u00e1n en la formaci\u00f3n y sensibilizaci\u00f3n en materia de trabajo infantil.\u00a0\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A trav\u00e9s de estas iniciativas, <\/span><b>el programa tambi\u00e9n proporciona a los exportadores, importadores, fabricantes, marcas y minoristas de cacao en las cadenas de suministro de cacao certificado Fairtrade una forma de apoyar a las organizaciones de productores para abordar y remediar el trabajo infantil y el trabajo forzoso<\/b><span style=\"font-weight: 400;\">, un requisito en el Est\u00e1ndar de Cacao Fairtrade actualizado.\u00a0\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">El requisito, que entr\u00f3 en vigor el 1 de julio de 2023, se aplica a las cadenas de suministro que se originan en regiones con un riesgo de trabajo infantil bien documentado, como Ghana y Costa de Marfil. Las empresas que compran cacao en t\u00e9rminos de balance de masas, lo que significa que el cacao puede mezclarse con fines de fabricaci\u00f3n despu\u00e9s de su exportaci\u00f3n, pueden contribuir al programa para cumplir con el requisito de apoyo a los comerciantes de los Est\u00e1ndares Fairtrade, a pesar de no tener un v\u00ednculo directo con cooperativas espec\u00edficas. Las empresas tambi\u00e9n pueden estar seguras de que su contribuci\u00f3n apoyar\u00e1 a las cooperativas de cacao de la regi\u00f3n de la que se abastecen.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">El Programa de Prevenci\u00f3n y Remediaci\u00f3n del Trabajo Infantil y el Trabajo Forzoso ha recibido m\u00e1s de <\/span><span style=\"font-weight: 400;\">500.000 euros de financiaci\u00f3n de organizaciones Fairtrade y socios comerciales, y se ampliar\u00e1 con contribuciones adicionales.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Los Est\u00e1ndares Fairtrade proh\u00edben estrictamente el trabajo infantil, y el cumplimiento es supervisado regularmente por FLOCERT, el certificador independiente de Fairtrade. Sin embargo, ning\u00fan sistema de certificaci\u00f3n puede garantizar que un producto est\u00e9 libre de trabajo infantil. Muchas cooperativas cuentan con un sistema de monitoreo y remediaci\u00f3n, pero muchas carecen de los recursos para abordar medidas de prevenci\u00f3n y remediaci\u00f3n m\u00e1s costosas. Y ah\u00ed es donde los programas financiados, como el de Fairtrade, ayudan a marcar la diferencia.\u00a0\u00a0\u00a0\u00a0\u00a0<\/span><\/p>\n<h3><b>Este programa no puede cubrir todas las necesidades, pero con \u00e9l podemos acelerar un cambio positivo que beneficie a todos<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">Fairtrade reconoce que este programa no puede cubrir todas las necesidades de inversi\u00f3n en actividades de prevenci\u00f3n y remediaci\u00f3n, sin embargo, <\/span><span style=\"font-weight: 400;\">paso a paso podemos ayudar a las cooperativas a financiar los proyectos que consideren m\u00e1s urgentes en el camino hacia la eliminaci\u00f3n del trabajo infantil y forzoso y proporcionar aprendizajes valiosos para una posible ampliaci\u00f3n. Con la combinaci\u00f3n de este programa y el requisito de que todos los actores de la cadena de suministro apoyen a las cooperativas, sabemos que podemos acelerar un cambio positivo que beneficie a todos.<\/span><\/p>\n<p><b>Fairtrade se compromete a luchar contra las causas fundamentales del trabajo infantil y el trabajo forzoso, y a promover los derechos de los ni\u00f1os<\/b><span style=\"font-weight: 400;\">. Adoptamos un enfoque hol\u00edstico, basado en tres mecanismos principales. Incluyen normas de certificaci\u00f3n s\u00f3lidas que establecen las normas sobre el trabajo infantil, pero que tambi\u00e9n ayudan a los agricultores a abordar las causas profundas. <\/span><b>Precios M\u00ednimos y Primas<\/b> <b>Fairtrade <\/b><span style=\"font-weight: 400;\">que permiten una mayor estabilidad y mayores ingresos para los hogares agr\u00edcolas y la opci\u00f3n de comenzar a invertir en beneficios comunitarios como las escuelas. Adem\u00e1s <\/span><b>del Precio M\u00ednimo y la Prima Fairtrade<\/b><span style=\"font-weight: 400;\"> obligatorios, tambi\u00e9n tenemos Precios de Referencia de Ingresos Dignos que las empresas pueden optar por pagar, adem\u00e1s.\u00a0<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>Alrededor de 1,5 millones de ni\u00f1os trabajan en las plantaciones de cacao en Costa de Marfil y Ghana, donde se producen dos tercios del cacao del mundo, seg\u00fan un estudio de NORC de la Universidad de Chicago. Fairtrade entiende que la pobreza es una de las causas fundamentales del trabajo infantil, y aunque no podemos [&hellip;]<\/p>","protected":false},"author":1,"featured_media":5150,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_ef_editorial_meta_date_first-draft-date":"","_ef_editorial_meta_paragraph_assignment":"","_ef_editorial_meta_checkbox_needs-photo":"","_ef_editorial_meta_number_word-count":"","footnotes":""},"categories":[149],"tags":[],"class_list":["post-5148","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-infancia"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El trabajo infantil se puede abordar paso a paso, y programa a programa. | Fairtrade<\/title>\n<meta name=\"description\" content=\"El trabajo infantil se puede abordar paso a paso, y programa a programa.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fairtrade.es\/pt\/comercio-justo-exploracao-infantil-2\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El trabajo infantil se puede abordar paso a paso, y programa a programa. | Fairtrade\" \/>\n<meta property=\"og:description\" content=\"El trabajo infantil se puede abordar paso a paso, y programa a programa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fairtrade.es\/pt\/comercio-justo-exploracao-infantil-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Fairtrade\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/fairtradeiberica\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-12T11:42:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-12T11:43:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fairtrade.es\/wp-content\/uploads\/2024\/06\/Bananas-Dominican-Republic-Las-Mercedes-2020-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"senda\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@fairtradeES\" \/>\n<meta name=\"twitter:site\" content=\"@fairtradeES\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"senda\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.fairtrade.es\\\/el-trabajo-infantil-se-puede-abordar-paso-a-paso-y-programa-a-programa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fairtrade.es\\\/el-trabajo-infantil-se-puede-abordar-paso-a-paso-y-programa-a-programa\\\/\"},\"author\":{\"name\":\"senda\",\"@id\":\"https:\\\/\\\/www.fairtrade.es\\\/#\\\/schema\\\/person\\\/2a8f05ec3db305005bb877b1b1fbb144\"},\"headline\":\"El trabajo infantil se puede abordar paso a paso, y programa a programa.\",\"datePublished\":\"2024-06-12T11:42:23+00:00\",\"dateModified\":\"2024-06-12T11:43:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.fairtrade.es\\\/el-trabajo-infantil-se-puede-abordar-paso-a-paso-y-programa-a-programa\\\/\"},\"wordCount\":916,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.fairtrade.es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fairtrade.es\\\/el-trabajo-infantil-se-puede-abordar-paso-a-paso-y-programa-a-programa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fairtrade.es\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Bananas-Dominican-Republic-Las-Mercedes-2020-scaled.jpg\",\"articleSection\":[\"Infancia\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.fairtrade.es\\\/el-trabajo-infantil-se-puede-abordar-paso-a-paso-y-programa-a-programa\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.fairtrade.es\\\/el-trabajo-infantil-se-puede-abordar-paso-a-paso-y-programa-a-programa\\\/\",\"url\":\"https:\\\/\\\/www.fairtrade.es\\\/el-trabajo-infantil-se-puede-abordar-paso-a-paso-y-programa-a-programa\\\/\",\"name\":\"El trabajo infantil se puede abordar paso a paso, y programa a programa. | Fairtrade\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.fairtrade.es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.fairtrade.es\\\/el-trabajo-infantil-se-puede-abordar-paso-a-paso-y-programa-a-programa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fairtrade.es\\\/el-trabajo-infantil-se-puede-abordar-paso-a-paso-y-programa-a-programa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.fairtrade.es\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Bananas-Dominican-Republic-Las-Mercedes-2020-scaled.jpg\",\"datePublished\":\"2024-06-12T11:42:23+00:00\",\"dateModified\":\"2024-06-12T11:43:09+00:00\",\"description\":\"El trabajo infantil se puede abordar paso a paso, y programa a programa.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.fairtrade.es\\\/el-trabajo-infantil-se-puede-abordar-paso-a-paso-y-programa-a-programa\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.fairtrade.es\\\/el-trabajo-infantil-se-puede-abordar-paso-a-paso-y-programa-a-programa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.fairtrade.es\\\/el-trabajo-infantil-se-puede-abordar-paso-a-paso-y-programa-a-programa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.fairtrade.es\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Bananas-Dominican-Republic-Las-Mercedes-2020-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.fairtrade.es\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/Bananas-Dominican-Republic-Las-Mercedes-2020-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.fairtrade.es\\\/el-trabajo-infantil-se-puede-abordar-paso-a-paso-y-programa-a-programa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.fairtrade.es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El trabajo infantil se puede abordar paso a paso, y programa a programa.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.fairtrade.es\\\/#website\",\"url\":\"https:\\\/\\\/www.fairtrade.es\\\/\",\"name\":\"Fairtrade\",\"description\":\"Sello l\u00edder de comercio justo\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.fairtrade.es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.fairtrade.es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.fairtrade.es\\\/#organization\",\"name\":\"Fairtrade Ib\u00e9rica\",\"url\":\"https:\\\/\\\/www.fairtrade.es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/www.fairtrade.es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.fairtrade.es\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Fairtrade-iberica-logo.png\",\"contentUrl\":\"https:\\\/\\\/www.fairtrade.es\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Fairtrade-iberica-logo.png\",\"width\":340,\"height\":407,\"caption\":\"Fairtrade Ib\u00e9rica\"},\"image\":{\"@id\":\"https:\\\/\\\/www.fairtrade.es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/fairtradeiberica\",\"https:\\\/\\\/x.com\\\/fairtradeES\",\"https:\\\/\\\/www.instagram.com\\\/fairtradeiberica\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/fairtrade-iberica\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/sellofairtrade\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.fairtrade.es\\\/#\\\/schema\\\/person\\\/2a8f05ec3db305005bb877b1b1fbb144\",\"name\":\"senda\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ad25152d66ab68f233ff1e771f5f5b61808045f5b306f63250027046f2b84c4?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ad25152d66ab68f233ff1e771f5f5b61808045f5b306f63250027046f2b84c4?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2ad25152d66ab68f233ff1e771f5f5b61808045f5b306f63250027046f2b84c4?s=96&d=mm&r=g\",\"caption\":\"senda\"},\"sameAs\":[\"http:\\\/\\\/localhost:8888\\\/fairtade\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El trabajo infantil se puede abordar paso a paso, y programa a programa. | Fairtrade","description":"El trabajo infantil se puede abordar paso a paso, y programa a programa.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fairtrade.es\/pt\/comercio-justo-exploracao-infantil-2\/","og_locale":"pt_PT","og_type":"article","og_title":"El trabajo infantil se puede abordar paso a paso, y programa a programa. | Fairtrade","og_description":"El trabajo infantil se puede abordar paso a paso, y programa a programa.","og_url":"https:\/\/www.fairtrade.es\/pt\/comercio-justo-exploracao-infantil-2\/","og_site_name":"Fairtrade","article_publisher":"https:\/\/www.facebook.com\/fairtradeiberica","article_published_time":"2024-06-12T11:42:23+00:00","article_modified_time":"2024-06-12T11:43:09+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/www.fairtrade.es\/wp-content\/uploads\/2024\/06\/Bananas-Dominican-Republic-Las-Mercedes-2020-scaled.jpg","type":"image\/jpeg"}],"author":"senda","twitter_card":"summary_large_image","twitter_creator":"@fairtradeES","twitter_site":"@fairtradeES","twitter_misc":{"Escrito por":"senda","Tempo estimado de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.fairtrade.es\/el-trabajo-infantil-se-puede-abordar-paso-a-paso-y-programa-a-programa\/#article","isPartOf":{"@id":"https:\/\/www.fairtrade.es\/el-trabajo-infantil-se-puede-abordar-paso-a-paso-y-programa-a-programa\/"},"author":{"name":"senda","@id":"https:\/\/www.fairtrade.es\/#\/schema\/person\/2a8f05ec3db305005bb877b1b1fbb144"},"headline":"El trabajo infantil se puede abordar paso a paso, y programa a programa.","datePublished":"2024-06-12T11:42:23+00:00","dateModified":"2024-06-12T11:43:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.fairtrade.es\/el-trabajo-infantil-se-puede-abordar-paso-a-paso-y-programa-a-programa\/"},"wordCount":916,"commentCount":0,"publisher":{"@id":"https:\/\/www.fairtrade.es\/#organization"},"image":{"@id":"https:\/\/www.fairtrade.es\/el-trabajo-infantil-se-puede-abordar-paso-a-paso-y-programa-a-programa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fairtrade.es\/wp-content\/uploads\/2024\/06\/Bananas-Dominican-Republic-Las-Mercedes-2020-scaled.jpg","articleSection":["Infancia"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.fairtrade.es\/el-trabajo-infantil-se-puede-abordar-paso-a-paso-y-programa-a-programa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.fairtrade.es\/el-trabajo-infantil-se-puede-abordar-paso-a-paso-y-programa-a-programa\/","url":"https:\/\/www.fairtrade.es\/el-trabajo-infantil-se-puede-abordar-paso-a-paso-y-programa-a-programa\/","name":"El trabajo infantil se puede abordar paso a paso, y programa a programa. | Fairtrade","isPartOf":{"@id":"https:\/\/www.fairtrade.es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fairtrade.es\/el-trabajo-infantil-se-puede-abordar-paso-a-paso-y-programa-a-programa\/#primaryimage"},"image":{"@id":"https:\/\/www.fairtrade.es\/el-trabajo-infantil-se-puede-abordar-paso-a-paso-y-programa-a-programa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fairtrade.es\/wp-content\/uploads\/2024\/06\/Bananas-Dominican-Republic-Las-Mercedes-2020-scaled.jpg","datePublished":"2024-06-12T11:42:23+00:00","dateModified":"2024-06-12T11:43:09+00:00","description":"El trabajo infantil se puede abordar paso a paso, y programa a programa.","breadcrumb":{"@id":"https:\/\/www.fairtrade.es\/el-trabajo-infantil-se-puede-abordar-paso-a-paso-y-programa-a-programa\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fairtrade.es\/el-trabajo-infantil-se-puede-abordar-paso-a-paso-y-programa-a-programa\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.fairtrade.es\/el-trabajo-infantil-se-puede-abordar-paso-a-paso-y-programa-a-programa\/#primaryimage","url":"https:\/\/www.fairtrade.es\/wp-content\/uploads\/2024\/06\/Bananas-Dominican-Republic-Las-Mercedes-2020-scaled.jpg","contentUrl":"https:\/\/www.fairtrade.es\/wp-content\/uploads\/2024\/06\/Bananas-Dominican-Republic-Las-Mercedes-2020-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/www.fairtrade.es\/el-trabajo-infantil-se-puede-abordar-paso-a-paso-y-programa-a-programa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.fairtrade.es\/"},{"@type":"ListItem","position":2,"name":"El trabajo infantil se puede abordar paso a paso, y programa a programa."}]},{"@type":"WebSite","@id":"https:\/\/www.fairtrade.es\/#website","url":"https:\/\/www.fairtrade.es\/","name":"Fairtrade","description":"Sello l\u00edder de comercio justo","publisher":{"@id":"https:\/\/www.fairtrade.es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fairtrade.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/www.fairtrade.es\/#organization","name":"Fairtrade Ib\u00e9rica","url":"https:\/\/www.fairtrade.es\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/www.fairtrade.es\/#\/schema\/logo\/image\/","url":"https:\/\/www.fairtrade.es\/wp-content\/uploads\/2022\/03\/Fairtrade-iberica-logo.png","contentUrl":"https:\/\/www.fairtrade.es\/wp-content\/uploads\/2022\/03\/Fairtrade-iberica-logo.png","width":340,"height":407,"caption":"Fairtrade Ib\u00e9rica"},"image":{"@id":"https:\/\/www.fairtrade.es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/fairtradeiberica","https:\/\/x.com\/fairtradeES","https:\/\/www.instagram.com\/fairtradeiberica\/","https:\/\/www.linkedin.com\/company\/fairtrade-iberica","https:\/\/www.youtube.com\/user\/sellofairtrade"]},{"@type":"Person","@id":"https:\/\/www.fairtrade.es\/#\/schema\/person\/2a8f05ec3db305005bb877b1b1fbb144","name":"senda","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/2ad25152d66ab68f233ff1e771f5f5b61808045f5b306f63250027046f2b84c4?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2ad25152d66ab68f233ff1e771f5f5b61808045f5b306f63250027046f2b84c4?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2ad25152d66ab68f233ff1e771f5f5b61808045f5b306f63250027046f2b84c4?s=96&d=mm&r=g","caption":"senda"},"sameAs":["http:\/\/localhost:8888\/fairtade"]}]}},"_links":{"self":[{"href":"https:\/\/www.fairtrade.es\/pt\/wp-json\/wp\/v2\/posts\/5148","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fairtrade.es\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fairtrade.es\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fairtrade.es\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fairtrade.es\/pt\/wp-json\/wp\/v2\/comments?post=5148"}],"version-history":[{"count":3,"href":"https:\/\/www.fairtrade.es\/pt\/wp-json\/wp\/v2\/posts\/5148\/revisions"}],"predecessor-version":[{"id":5153,"href":"https:\/\/www.fairtrade.es\/pt\/wp-json\/wp\/v2\/posts\/5148\/revisions\/5153"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fairtrade.es\/pt\/wp-json\/wp\/v2\/media\/5150"}],"wp:attachment":[{"href":"https:\/\/www.fairtrade.es\/pt\/wp-json\/wp\/v2\/media?parent=5148"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fairtrade.es\/pt\/wp-json\/wp\/v2\/categories?post=5148"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fairtrade.es\/pt\/wp-json\/wp\/v2\/tags?post=5148"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}